{"id":61025,"date":"2022-03-02T17:30:50","date_gmt":"2022-03-02T16:30:50","guid":{"rendered":"https:\/\/mont-roig.cat\/actualitat\/noticies\/lajuntament-de-mont-roig-del-camp-ofereix-suport-a-la-comunitat-ucrainesa-per-les-accions-que-vulguin-dur-a-terme\/"},"modified":"2022-03-02T17:41:39","modified_gmt":"2022-03-02T16:41:39","slug":"lajuntament-de-mont-roig-del-camp-ofereix-suport-a-la-comunitat-ucrainesa-per-les-accions-que-vulguin-dur-a-terme","status":"publish","type":"post","link":"https:\/\/mont-roig.cat\/es\/actualitat\/noticies\/lajuntament-de-mont-roig-del-camp-ofereix-suport-a-la-comunitat-ucrainesa-per-les-accions-que-vulguin-dur-a-terme\/","title":{"rendered":"El Ayuntamiento de Mont-roig del Camp ofrece apoyo a la comunidad ucraniana para las acciones que quieran llevar a cabo"},"content":{"rendered":"<p>&nbsp;<\/p>\n<div id=\"attachment_61009\" style=\"width: 309px\" class=\"wp-caption alignright\"><a href=\"https:\/\/mont-roig.cat\/wp-content\/uploads\/3623c36c-106b-4581-b236-f6765234dba8.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-61009\" class=\"wp-image-61009\" src=\"https:\/\/mont-roig.cat\/wp-content\/uploads\/3623c36c-106b-4581-b236-f6765234dba8-500x375.jpg\" alt=\"\" width=\"299\" height=\"224\" srcset=\"https:\/\/mont-roig.cat\/wp-content\/uploads\/3623c36c-106b-4581-b236-f6765234dba8-500x375.jpg 500w, https:\/\/mont-roig.cat\/wp-content\/uploads\/3623c36c-106b-4581-b236-f6765234dba8-1024x768.jpg 1024w, https:\/\/mont-roig.cat\/wp-content\/uploads\/3623c36c-106b-4581-b236-f6765234dba8-768x576.jpg 768w, https:\/\/mont-roig.cat\/wp-content\/uploads\/3623c36c-106b-4581-b236-f6765234dba8-1536x1152.jpg 1536w, https:\/\/mont-roig.cat\/wp-content\/uploads\/3623c36c-106b-4581-b236-f6765234dba8-463x348.jpg 463w, https:\/\/mont-roig.cat\/wp-content\/uploads\/3623c36c-106b-4581-b236-f6765234dba8.jpg 1600w\" sizes=\"auto, (max-width: 299px) 100vw, 299px\" \/><\/a><p id=\"caption-attachment-61009\" class=\"wp-caption-text\">Reuni\u00f3n entre el alcalde Fran Morancho y parte del gobierno municipal con un grupo de ucranianos del municipio.<\/p><\/div>\n<ul>\n<li><strong>El alcalde de Mont-roig del Camp y parte del equipo de gobierno reciben una treintena de ucranianos del municipio antes de la concentraci\u00f3n de rechazo a la guerra<\/strong><\/li>\n<\/ul>\n<p>El alcalde de Mont-roig del Camp, Fran Morancho, acompa\u00f1ado de varios concejales y concejalas del gobierno municipal, se reuni\u00f3 anoche con una treintena de ciudadanos y ciudadanas de Ucrania residentes en el municipio. El encuentro se llev\u00f3 a cabo poco antes de la concentraci\u00f3n que tuvo lugar en Mont-roig y en Miami Platja en favor de la paz y de rechazo al ataque ruso. Morancho, en el transcurso del encuentro, traslad\u00f3 a la comunidad ucraniana el apoyo y predisposici\u00f3n del Ayuntamiento para las acciones que quieran llevar a cabo en los pr\u00f3ximos d\u00edas o semanas.<\/p>\n<p>Por su parte, los representantes de la comunidad ucraniana pidieron un espacio para poder organizar la recogida de ayuda humanitaria para enviar a su pa\u00eds. En este sentido, se les comunic\u00f3 que se pondr\u00e1 a su disposici\u00f3n un local y que se les ayudar\u00e1 a difundir entre la ciudadan\u00eda de las iniciativas solidarias que lleven a cabo en esta l\u00ednea.<\/p>\n<p>Tambi\u00e9n se les traslad\u00f3 el compromiso del Ayuntamiento de Mont-roig del Camp de estar a su lado en la tramitaci\u00f3n de permisos de residencia, asistencia social o escolarizaci\u00f3n de los ni\u00f1os que puedan llegar al municipio huyendo de la guerra.<\/p>\n<p>As\u00ed pues, el Ayuntamiento de Mont-roig del Camp informar\u00e1 a trav\u00e9s de sus medios de comunicaci\u00f3n municipales cualquier novedad e informaci\u00f3n relativa a las acciones que lleve a cabo la comunidad ucraniana y la recogida de ayuda humanitaria.<\/p>\n<p>Por otra parte, y a falta de una mayor concreci\u00f3n hay que recordar que la Uni\u00f3n Europea est\u00e1 trabajando para facilitar la acogida de ciudadan\u00eda ucraniana o para prorrogar la estancia en nuestro pa\u00eds de la poblaci\u00f3n de ese pa\u00eds que ya hab\u00eda huido o se encuentra entre nosotros. En estos momentos se est\u00e1 a la espera de la decisi\u00f3n final del Consejo de Europa.<\/p>\n<p><strong>Concentraciones de rechazo a la guerra<\/strong><\/p>\n<p>Por \u00faltimo, cabe destacar que a las concentraciones que tuvieron lugar anoche en Mont-roig y en Miami Platja asistieron un centenar de personas que mostraron su apoyo a la poblaci\u00f3n ucraniana y en contra de la agresi\u00f3n unilateral de Rusia. Durante el acto, cogieron la palabra algunos miembros de la comunidad ucraniana, entre ellos una vecina de Miami Platja y otra de Mont-roig, que agradecieron el apoyo y trasladaron que cualquier tipo de ayuda que se pueda dar ser\u00e1 bienvenida.<\/p>\n\n\t\t<!-- MasterSlider -->\n\t\t<div id=\"P_MS6a5756664b8cd\" class=\"master-slider-parent master-slider-gallery   ms-parent-id-0\"  >\n\n\t\t\t\n\t\t\t<!-- MasterSlider Main -->\n\t\t\t<div id=\"MS6a5756664b8cd\" class=\"master-slider ms-skin-default\" >\n\t\t\t\t \t\t\t\t \n\t\t\t<div  class=\"ms-slide\" data-delay=\"3\"    >\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/mont-roig.cat\/wp-content\/plugins\/masterslider\/public\/assets\/css\/blank.gif\" alt=\"11e2394e-8bd8-4bbe-bd94-1628f6edb3c8\" title=\"11e2394e-8bd8-4bbe-bd94-1628f6edb3c8\" data-src=\"https:\/\/mont-roig.cat\/wp-content\/uploadsArray\" \/>\n\t<a href=\"https:\/\/mont-roig.cat\/es\/actualitat\/noticies\/lajuntament-de-mont-roig-del-camp-ofereix-suport-a-la-comunitat-ucrainesa-per-les-accions-que-vulguin-dur-a-terme\/11e2394e-8bd8-4bbe-bd94-1628f6edb3c8-2\/\" target=\"_self\"    >11e2394e-8bd8-4bbe-bd94-1628f6edb3c8<\/a>\n\n\t\t\t\t\t<div class=\"ms-info\">11e2394e-8bd8-4bbe-bd94-1628f6edb3c8<\/div>\n\n\n\t<img decoding=\"async\" class=\"ms-thumb\" src=\"https:\/\/mont-roig.cat\/wp-content\/uploadsArray\" alt=\"11e2394e-8bd8-4bbe-bd94-1628f6edb3c8\" \/>\n\t\t\t\t<\/div>\n\t\t\t<div  class=\"ms-slide\" data-delay=\"3\"    >\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/mont-roig.cat\/wp-content\/plugins\/masterslider\/public\/assets\/css\/blank.gif\" alt=\"c0215489-5356-4689-a021-556679ec3ede\" title=\"c0215489-5356-4689-a021-556679ec3ede\" data-src=\"https:\/\/mont-roig.cat\/wp-content\/uploadsArray\" \/>\n\t<a href=\"https:\/\/mont-roig.cat\/es\/actualitat\/noticies\/lajuntament-de-mont-roig-del-camp-ofereix-suport-a-la-comunitat-ucrainesa-per-les-accions-que-vulguin-dur-a-terme\/c0215489-5356-4689-a021-556679ec3ede-2\/\" target=\"_self\"    >c0215489-5356-4689-a021-556679ec3ede<\/a>\n\n\t\t\t\t\t<div class=\"ms-info\">c0215489-5356-4689-a021-556679ec3ede<\/div>\n\n\n\t<img decoding=\"async\" class=\"ms-thumb\" src=\"https:\/\/mont-roig.cat\/wp-content\/uploadsArray\" alt=\"c0215489-5356-4689-a021-556679ec3ede\" \/>\n\t\t\t\t<\/div>\n\t\t\t<div  class=\"ms-slide\" data-delay=\"3\"    >\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/mont-roig.cat\/wp-content\/plugins\/masterslider\/public\/assets\/css\/blank.gif\" alt=\"6e898b41-e893-4f7d-a352-f6b2d6b5eafc\" title=\"6e898b41-e893-4f7d-a352-f6b2d6b5eafc\" data-src=\"https:\/\/mont-roig.cat\/wp-content\/uploadsArray\" \/>\n\t<a href=\"https:\/\/mont-roig.cat\/es\/actualitat\/noticies\/lajuntament-de-mont-roig-del-camp-ofereix-suport-a-la-comunitat-ucrainesa-per-les-accions-que-vulguin-dur-a-terme\/6e898b41-e893-4f7d-a352-f6b2d6b5eafc-2\/\" target=\"_self\"    >6e898b41-e893-4f7d-a352-f6b2d6b5eafc<\/a>\n\n\t\t\t\t\t<div class=\"ms-info\">6e898b41-e893-4f7d-a352-f6b2d6b5eafc<\/div>\n\n\n\t<img decoding=\"async\" class=\"ms-thumb\" src=\"https:\/\/mont-roig.cat\/wp-content\/uploadsArray\" alt=\"6e898b41-e893-4f7d-a352-f6b2d6b5eafc\" \/>\n\t\t\t\t<\/div>\n\t\t\t<div  class=\"ms-slide\" data-delay=\"3\"    >\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/mont-roig.cat\/wp-content\/plugins\/masterslider\/public\/assets\/css\/blank.gif\" alt=\"d0f8348e-bd62-41a6-bd88-a0be6a8ba6fc\" title=\"d0f8348e-bd62-41a6-bd88-a0be6a8ba6fc\" data-src=\"https:\/\/mont-roig.cat\/wp-content\/uploadsArray\" \/>\n\t<a href=\"https:\/\/mont-roig.cat\/es\/actualitat\/noticies\/lajuntament-de-mont-roig-del-camp-ofereix-suport-a-la-comunitat-ucrainesa-per-les-accions-que-vulguin-dur-a-terme\/d0f8348e-bd62-41a6-bd88-a0be6a8ba6fc-2\/\" target=\"_self\"    >d0f8348e-bd62-41a6-bd88-a0be6a8ba6fc<\/a>\n\n\t\t\t\t\t<div class=\"ms-info\">d0f8348e-bd62-41a6-bd88-a0be6a8ba6fc<\/div>\n\n\n\t<img decoding=\"async\" class=\"ms-thumb\" src=\"https:\/\/mont-roig.cat\/wp-content\/uploadsArray\" alt=\"d0f8348e-bd62-41a6-bd88-a0be6a8ba6fc\" \/>\n\t\t\t\t<\/div>\n\t\t\t<div  class=\"ms-slide\" data-delay=\"3\"    >\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/mont-roig.cat\/wp-content\/plugins\/masterslider\/public\/assets\/css\/blank.gif\" alt=\"e13959c8-7da4-4f39-8eb8-02afefab3408\" title=\"e13959c8-7da4-4f39-8eb8-02afefab3408\" data-src=\"https:\/\/mont-roig.cat\/wp-content\/uploadsArray\" \/>\n\t<a href=\"https:\/\/mont-roig.cat\/es\/actualitat\/noticies\/lajuntament-de-mont-roig-del-camp-ofereix-suport-a-la-comunitat-ucrainesa-per-les-accions-que-vulguin-dur-a-terme\/e13959c8-7da4-4f39-8eb8-02afefab3408-2\/\" target=\"_self\"    >e13959c8-7da4-4f39-8eb8-02afefab3408<\/a>\n\n\t\t\t\t\t<div class=\"ms-info\">e13959c8-7da4-4f39-8eb8-02afefab3408<\/div>\n\n\n\t<img decoding=\"async\" class=\"ms-thumb\" src=\"https:\/\/mont-roig.cat\/wp-content\/uploadsArray\" alt=\"e13959c8-7da4-4f39-8eb8-02afefab3408\" \/>\n\t\t\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t\t<!-- END MasterSlider Main -->\n\n\t\t\t \n\t\t<\/div>\n\t\t<!-- END MasterSlider -->\n\n\t\t<script>\n\t\t( window.MSReady = window.MSReady || [] ).push( function( $ ) {\n\n\t\t\t\"use strict\";\n\t\t\tvar masterslider_b8cd = new MasterSlider();\n\n\t\t\t\/\/ slider controls\n\t\t\tmasterslider_b8cd.control('arrows'     ,{ autohide:true, overVideo:true  });\n\t\t\tmasterslider_b8cd.control('thumblist'  ,{ autohide:false, overVideo:true, dir:'h', speed:17, inset:false, arrows:false, hover:false, customClass:'', align:'bottom',type:'thumbs', margin:2, width:140, height:80, space:2, fillMode:'fill'  });\n\t\t\tmasterslider_b8cd.control('slideinfo'  ,{ autohide:true, overVideo:true, dir:'h', align:'bottom',inset:true , margin:80  , size:30 });\n\t\t\t\/\/ slider setup\n\t\t\tmasterslider_b8cd.setup(\"MS6a5756664b8cd\", {\n\t\t\t\twidth           : 960,\n\t\t\t\theight          : 540,\n\t\t\t\tminHeight       : 0,\n\t\t\t\tspace           : 0,\n\t\t\t\tstart           : 1,\n\t\t\t\tgrabCursor      : true,\n\t\t\t\tswipe           : true,\n\t\t\t\tmouse           : true,\n\t\t\t\tkeyboard        : false,\n\t\t\t\tlayout          : \"fillwidth\",\n\t\t\t\twheel           : false,\n\t\t\t\tautoplay        : false,\n                instantStartLayers:false,\n\t\t\t\tmobileBGVideo:false,\n\t\t\t\tloop            : false,\n\t\t\t\tshuffle         : false,\n\t\t\t\tpreload         : 3,\n\t\t\t\theightLimit     : false,\n\t\t\t\tautoHeight      : false,\n\t\t\t\tsmoothHeight    : true,\n\t\t\t\tendPause        : false,\n\t\t\t\toverPause       : false,\n\t\t\t\tfillMode        : \"fill\",\n\t\t\t\tcenterControls  : true,\n\t\t\t\tstartOnAppear   : false,\n\t\t\t\tlayersMode      : \"center\",\n\t\t\t\tautofillTarget  : \"\",\n\t\t\t\thideLayers      : false,\n\t\t\t\tfullscreenMargin: 0,\n\t\t\t\tspeed           : 17,\n\t\t\t\tdir             : \"h\",\n\t\t\t\tparallaxMode    : 'swipe',\n\t\t\t\tview            : \"basic\"\n\t\t\t});\n\n\t\t\t\n\t\t\twindow.masterslider_instances = window.masterslider_instances || [];\n\t\t\twindow.masterslider_instances.push( masterslider_b8cd );\n\t\t});\n\t\t<\/script>\n\n\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; El alcalde de Mont-roig del Camp y parte del equipo de gobierno reciben una treintena de ucranianos del municipio antes de la concentraci\u00f3n de rechazo a la guerra El alcalde de Mont-roig del Camp, Fran Morancho, acompa\u00f1ado de varios concejales y concejalas del gobierno municipal, se reuni\u00f3 anoche con una treintena de ciudadanos y [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":61010,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[156,98],"tags":[],"class_list":["post-61025","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alcalde-es","category-ayuntamiento"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Ayuntamiento de Mont-roig del Camp ofrece apoyo a la comunidad ucraniana para las acciones que quieran llevar a cabo - Ajuntament de Mont-roig del Camp<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mont-roig.cat\/es\/actualitat\/noticies\/lajuntament-de-mont-roig-del-camp-ofereix-suport-a-la-comunitat-ucrainesa-per-les-accions-que-vulguin-dur-a-terme\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Ayuntamiento de Mont-roig del Camp ofrece apoyo a la comunidad ucraniana para las acciones que quieran llevar a cabo - Ajuntament de Mont-roig del Camp\" \/>\n<meta property=\"og:description\" content=\"&nbsp; El alcalde de Mont-roig del Camp y parte del equipo de gobierno reciben una treintena de ucranianos del municipio antes de la concentraci\u00f3n de rechazo a la guerra El alcalde de Mont-roig del Camp, Fran Morancho, acompa\u00f1ado de varios concejales y concejalas del gobierno municipal, se reuni\u00f3 anoche con una treintena de ciudadanos y [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mont-roig.cat\/es\/actualitat\/noticies\/lajuntament-de-mont-roig-del-camp-ofereix-suport-a-la-comunitat-ucrainesa-per-les-accions-que-vulguin-dur-a-terme\/\" \/>\n<meta property=\"og:site_name\" content=\"Ajuntament de Mont-roig del Camp\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-02T16:30:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-02T16:41:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mont-roig.cat\/wp-content\/uploads\/3623c36c-106b-4581-b236-f6765234dba8.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"comunicacio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunicacio\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mont-roig.cat\\\/es\\\/actualitat\\\/noticies\\\/lajuntament-de-mont-roig-del-camp-ofereix-suport-a-la-comunitat-ucrainesa-per-les-accions-que-vulguin-dur-a-terme\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mont-roig.cat\\\/es\\\/actualitat\\\/noticies\\\/lajuntament-de-mont-roig-del-camp-ofereix-suport-a-la-comunitat-ucrainesa-per-les-accions-que-vulguin-dur-a-terme\\\/\"},\"author\":{\"name\":\"comunicacio\",\"@id\":\"https:\\\/\\\/mont-roig.cat\\\/es\\\/#\\\/schema\\\/person\\\/1f73e7b5e6f9dd122e8a6f14f310ac5e\"},\"headline\":\"El Ayuntamiento de Mont-roig del Camp ofrece apoyo a la comunidad ucraniana para las acciones que quieran llevar a cabo\",\"datePublished\":\"2022-03-02T16:30:50+00:00\",\"dateModified\":\"2022-03-02T16:41:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mont-roig.cat\\\/es\\\/actualitat\\\/noticies\\\/lajuntament-de-mont-roig-del-camp-ofereix-suport-a-la-comunitat-ucrainesa-per-les-accions-que-vulguin-dur-a-terme\\\/\"},\"wordCount\":495,\"image\":{\"@id\":\"https:\\\/\\\/mont-roig.cat\\\/es\\\/actualitat\\\/noticies\\\/lajuntament-de-mont-roig-del-camp-ofereix-suport-a-la-comunitat-ucrainesa-per-les-accions-que-vulguin-dur-a-terme\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mont-roig.cat\\\/wp-content\\\/uploads\\\/3623c36c-106b-4581-b236-f6765234dba8.jpg\",\"articleSection\":[\"Alcalde\",\"Ayuntamiento\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mont-roig.cat\\\/es\\\/actualitat\\\/noticies\\\/lajuntament-de-mont-roig-del-camp-ofereix-suport-a-la-comunitat-ucrainesa-per-les-accions-que-vulguin-dur-a-terme\\\/\",\"url\":\"https:\\\/\\\/mont-roig.cat\\\/es\\\/actualitat\\\/noticies\\\/lajuntament-de-mont-roig-del-camp-ofereix-suport-a-la-comunitat-ucrainesa-per-les-accions-que-vulguin-dur-a-terme\\\/\",\"name\":\"El Ayuntamiento de Mont-roig del Camp ofrece apoyo a la comunidad ucraniana para las acciones que quieran llevar a cabo - Ajuntament de Mont-roig del Camp\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mont-roig.cat\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mont-roig.cat\\\/es\\\/actualitat\\\/noticies\\\/lajuntament-de-mont-roig-del-camp-ofereix-suport-a-la-comunitat-ucrainesa-per-les-accions-que-vulguin-dur-a-terme\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mont-roig.cat\\\/es\\\/actualitat\\\/noticies\\\/lajuntament-de-mont-roig-del-camp-ofereix-suport-a-la-comunitat-ucrainesa-per-les-accions-que-vulguin-dur-a-terme\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mont-roig.cat\\\/wp-content\\\/uploads\\\/3623c36c-106b-4581-b236-f6765234dba8.jpg\",\"datePublished\":\"2022-03-02T16:30:50+00:00\",\"dateModified\":\"2022-03-02T16:41:39+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/mont-roig.cat\\\/es\\\/#\\\/schema\\\/person\\\/1f73e7b5e6f9dd122e8a6f14f310ac5e\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mont-roig.cat\\\/es\\\/actualitat\\\/noticies\\\/lajuntament-de-mont-roig-del-camp-ofereix-suport-a-la-comunitat-ucrainesa-per-les-accions-que-vulguin-dur-a-terme\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mont-roig.cat\\\/es\\\/actualitat\\\/noticies\\\/lajuntament-de-mont-roig-del-camp-ofereix-suport-a-la-comunitat-ucrainesa-per-les-accions-que-vulguin-dur-a-terme\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/mont-roig.cat\\\/es\\\/actualitat\\\/noticies\\\/lajuntament-de-mont-roig-del-camp-ofereix-suport-a-la-comunitat-ucrainesa-per-les-accions-que-vulguin-dur-a-terme\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mont-roig.cat\\\/wp-content\\\/uploads\\\/3623c36c-106b-4581-b236-f6765234dba8.jpg\",\"contentUrl\":\"https:\\\/\\\/mont-roig.cat\\\/wp-content\\\/uploads\\\/3623c36c-106b-4581-b236-f6765234dba8.jpg\",\"width\":1600,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mont-roig.cat\\\/es\\\/actualitat\\\/noticies\\\/lajuntament-de-mont-roig-del-camp-ofereix-suport-a-la-comunitat-ucrainesa-per-les-accions-que-vulguin-dur-a-terme\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/mont-roig.cat\\\/es\\\/pagina-de-inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Ayuntamiento de Mont-roig del Camp ofrece apoyo a la comunidad ucraniana para las acciones que quieran llevar a cabo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mont-roig.cat\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/mont-roig.cat\\\/es\\\/\",\"name\":\"Ajuntament de Mont-roig del Camp\",\"description\":\"Tota la informaci\u00f3 sobre la instituci\u00f3, els seus \u00f2rgans de govern, actualitat, serveis i molt m\u00e9s.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mont-roig.cat\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mont-roig.cat\\\/es\\\/#\\\/schema\\\/person\\\/1f73e7b5e6f9dd122e8a6f14f310ac5e\",\"name\":\"comunicacio\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/98944333e7a877670a64f8d10f0cb680ab2c9ebc4efc43945ef004b52b5ad28c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/98944333e7a877670a64f8d10f0cb680ab2c9ebc4efc43945ef004b52b5ad28c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/98944333e7a877670a64f8d10f0cb680ab2c9ebc4efc43945ef004b52b5ad28c?s=96&d=mm&r=g\",\"caption\":\"comunicacio\"},\"url\":\"https:\\\/\\\/mont-roig.cat\\\/es\\\/actualitat\\\/noticies\\\/author\\\/comunicacio\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Ayuntamiento de Mont-roig del Camp ofrece apoyo a la comunidad ucraniana para las acciones que quieran llevar a cabo - Ajuntament de Mont-roig del Camp","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mont-roig.cat\/es\/actualitat\/noticies\/lajuntament-de-mont-roig-del-camp-ofereix-suport-a-la-comunitat-ucrainesa-per-les-accions-que-vulguin-dur-a-terme\/","og_locale":"es_ES","og_type":"article","og_title":"El Ayuntamiento de Mont-roig del Camp ofrece apoyo a la comunidad ucraniana para las acciones que quieran llevar a cabo - Ajuntament de Mont-roig del Camp","og_description":"&nbsp; El alcalde de Mont-roig del Camp y parte del equipo de gobierno reciben una treintena de ucranianos del municipio antes de la concentraci\u00f3n de rechazo a la guerra El alcalde de Mont-roig del Camp, Fran Morancho, acompa\u00f1ado de varios concejales y concejalas del gobierno municipal, se reuni\u00f3 anoche con una treintena de ciudadanos y [&hellip;]","og_url":"https:\/\/mont-roig.cat\/es\/actualitat\/noticies\/lajuntament-de-mont-roig-del-camp-ofereix-suport-a-la-comunitat-ucrainesa-per-les-accions-que-vulguin-dur-a-terme\/","og_site_name":"Ajuntament de Mont-roig del Camp","article_published_time":"2022-03-02T16:30:50+00:00","article_modified_time":"2022-03-02T16:41:39+00:00","og_image":[{"width":1600,"height":1200,"url":"https:\/\/mont-roig.cat\/wp-content\/uploads\/3623c36c-106b-4581-b236-f6765234dba8.jpg","type":"image\/jpeg"}],"author":"comunicacio","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"comunicacio","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mont-roig.cat\/es\/actualitat\/noticies\/lajuntament-de-mont-roig-del-camp-ofereix-suport-a-la-comunitat-ucrainesa-per-les-accions-que-vulguin-dur-a-terme\/#article","isPartOf":{"@id":"https:\/\/mont-roig.cat\/es\/actualitat\/noticies\/lajuntament-de-mont-roig-del-camp-ofereix-suport-a-la-comunitat-ucrainesa-per-les-accions-que-vulguin-dur-a-terme\/"},"author":{"name":"comunicacio","@id":"https:\/\/mont-roig.cat\/es\/#\/schema\/person\/1f73e7b5e6f9dd122e8a6f14f310ac5e"},"headline":"El Ayuntamiento de Mont-roig del Camp ofrece apoyo a la comunidad ucraniana para las acciones que quieran llevar a cabo","datePublished":"2022-03-02T16:30:50+00:00","dateModified":"2022-03-02T16:41:39+00:00","mainEntityOfPage":{"@id":"https:\/\/mont-roig.cat\/es\/actualitat\/noticies\/lajuntament-de-mont-roig-del-camp-ofereix-suport-a-la-comunitat-ucrainesa-per-les-accions-que-vulguin-dur-a-terme\/"},"wordCount":495,"image":{"@id":"https:\/\/mont-roig.cat\/es\/actualitat\/noticies\/lajuntament-de-mont-roig-del-camp-ofereix-suport-a-la-comunitat-ucrainesa-per-les-accions-que-vulguin-dur-a-terme\/#primaryimage"},"thumbnailUrl":"https:\/\/mont-roig.cat\/wp-content\/uploads\/3623c36c-106b-4581-b236-f6765234dba8.jpg","articleSection":["Alcalde","Ayuntamiento"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/mont-roig.cat\/es\/actualitat\/noticies\/lajuntament-de-mont-roig-del-camp-ofereix-suport-a-la-comunitat-ucrainesa-per-les-accions-que-vulguin-dur-a-terme\/","url":"https:\/\/mont-roig.cat\/es\/actualitat\/noticies\/lajuntament-de-mont-roig-del-camp-ofereix-suport-a-la-comunitat-ucrainesa-per-les-accions-que-vulguin-dur-a-terme\/","name":"El Ayuntamiento de Mont-roig del Camp ofrece apoyo a la comunidad ucraniana para las acciones que quieran llevar a cabo - Ajuntament de Mont-roig del Camp","isPartOf":{"@id":"https:\/\/mont-roig.cat\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mont-roig.cat\/es\/actualitat\/noticies\/lajuntament-de-mont-roig-del-camp-ofereix-suport-a-la-comunitat-ucrainesa-per-les-accions-que-vulguin-dur-a-terme\/#primaryimage"},"image":{"@id":"https:\/\/mont-roig.cat\/es\/actualitat\/noticies\/lajuntament-de-mont-roig-del-camp-ofereix-suport-a-la-comunitat-ucrainesa-per-les-accions-que-vulguin-dur-a-terme\/#primaryimage"},"thumbnailUrl":"https:\/\/mont-roig.cat\/wp-content\/uploads\/3623c36c-106b-4581-b236-f6765234dba8.jpg","datePublished":"2022-03-02T16:30:50+00:00","dateModified":"2022-03-02T16:41:39+00:00","author":{"@id":"https:\/\/mont-roig.cat\/es\/#\/schema\/person\/1f73e7b5e6f9dd122e8a6f14f310ac5e"},"breadcrumb":{"@id":"https:\/\/mont-roig.cat\/es\/actualitat\/noticies\/lajuntament-de-mont-roig-del-camp-ofereix-suport-a-la-comunitat-ucrainesa-per-les-accions-que-vulguin-dur-a-terme\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mont-roig.cat\/es\/actualitat\/noticies\/lajuntament-de-mont-roig-del-camp-ofereix-suport-a-la-comunitat-ucrainesa-per-les-accions-que-vulguin-dur-a-terme\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/mont-roig.cat\/es\/actualitat\/noticies\/lajuntament-de-mont-roig-del-camp-ofereix-suport-a-la-comunitat-ucrainesa-per-les-accions-que-vulguin-dur-a-terme\/#primaryimage","url":"https:\/\/mont-roig.cat\/wp-content\/uploads\/3623c36c-106b-4581-b236-f6765234dba8.jpg","contentUrl":"https:\/\/mont-roig.cat\/wp-content\/uploads\/3623c36c-106b-4581-b236-f6765234dba8.jpg","width":1600,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/mont-roig.cat\/es\/actualitat\/noticies\/lajuntament-de-mont-roig-del-camp-ofereix-suport-a-la-comunitat-ucrainesa-per-les-accions-que-vulguin-dur-a-terme\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/mont-roig.cat\/es\/pagina-de-inicio\/"},{"@type":"ListItem","position":2,"name":"El Ayuntamiento de Mont-roig del Camp ofrece apoyo a la comunidad ucraniana para las acciones que quieran llevar a cabo"}]},{"@type":"WebSite","@id":"https:\/\/mont-roig.cat\/es\/#website","url":"https:\/\/mont-roig.cat\/es\/","name":"Ajuntament de Mont-roig del Camp","description":"Tota la informaci\u00f3 sobre la instituci\u00f3, els seus \u00f2rgans de govern, actualitat, serveis i molt m\u00e9s.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mont-roig.cat\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/mont-roig.cat\/es\/#\/schema\/person\/1f73e7b5e6f9dd122e8a6f14f310ac5e","name":"comunicacio","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/98944333e7a877670a64f8d10f0cb680ab2c9ebc4efc43945ef004b52b5ad28c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/98944333e7a877670a64f8d10f0cb680ab2c9ebc4efc43945ef004b52b5ad28c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/98944333e7a877670a64f8d10f0cb680ab2c9ebc4efc43945ef004b52b5ad28c?s=96&d=mm&r=g","caption":"comunicacio"},"url":"https:\/\/mont-roig.cat\/es\/actualitat\/noticies\/author\/comunicacio\/"}]}},"_links":{"self":[{"href":"https:\/\/mont-roig.cat\/es\/wp-json\/wp\/v2\/posts\/61025","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mont-roig.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mont-roig.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mont-roig.cat\/es\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/mont-roig.cat\/es\/wp-json\/wp\/v2\/comments?post=61025"}],"version-history":[{"count":2,"href":"https:\/\/mont-roig.cat\/es\/wp-json\/wp\/v2\/posts\/61025\/revisions"}],"predecessor-version":[{"id":61026,"href":"https:\/\/mont-roig.cat\/es\/wp-json\/wp\/v2\/posts\/61025\/revisions\/61026"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mont-roig.cat\/es\/wp-json\/wp\/v2\/media\/61010"}],"wp:attachment":[{"href":"https:\/\/mont-roig.cat\/es\/wp-json\/wp\/v2\/media?parent=61025"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mont-roig.cat\/es\/wp-json\/wp\/v2\/categories?post=61025"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mont-roig.cat\/es\/wp-json\/wp\/v2\/tags?post=61025"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}